{"id":18,"date":"2025-05-23T00:40:06","date_gmt":"2025-05-23T00:40:06","guid":{"rendered":"http:\/\/kfac.fr\/?page_id=18"},"modified":"2026-06-17T08:33:20","modified_gmt":"2026-06-17T08:33:20","slug":"18-2","status":"publish","type":"page","link":"https:\/\/kfac.fr\/ko\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#0033a0&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0.5) 0%|rgba(0,0,0,0.5) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/03\/ju-seok-header.jpg\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb background_blend=\u00a0\u00bbluminosity\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb0vw||0px||false|false\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bbnone\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb700ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/03\/logo-kfac-512-degrade.png\u00a0\u00bb alt=\u00a0\u00bbKFAC\u00a0\u00bb title_text=\u00a0\u00bblogo-kfac-512-degrade\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb30%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb max_height=\u00a0\u00bb34vw\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb500ms\u00a0\u00bb scroll_fade=\u00a0\u00bb0|50|50|100|100%|100|0%\u00a0\u00bb motion_trigger_start=\u00a0\u00bbbottom\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb570b9dd5-f93c-4c6f-b25e-8e2ce2bd2046&Prime; header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb3vw\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|-4|0|5&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>korean french art connection<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#0047a0&Prime; background_image=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/03\/logo-kfac-1500-degrade.png\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb background_blend=\u00a0\u00bbsoft-light\u00a0\u00bb custom_padding=\u00a0\u00bb3vw||3vw||true|false\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb3342aa0e-8878-4ddf-8998-a980078b3d7d\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb28px\u00a0\u00bb header_2_font=\u00a0\u00bb||on||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#cecece\u00a0\u00bb header_2_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb scroll_horizontal_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|4|0|0&Prime; scroll_fade_enable=\u00a0\u00bbon\u00a0\u00bb motion_trigger_start=\u00a0\u00bbbottom\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>KOREAN FRENCH ART CONNECTION 2026<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdf660a45-fa1a-4116-bcd7-eb754b4d84f3&Prime; text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb28px\u00a0\u00bb header_4_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_4_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_delay=\u00a0\u00bb250ms\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|-4|0|0&Prime; scroll_fade_enable=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 class=\"ds-markdown-paragraph\"><span>Apr\u00e8s une premi\u00e8re ann\u00e9e riche en \u00e9changes, <strong>Korean French Art Connection<\/strong> poursuit sa mission en 2026 : cr\u00e9er des passerelles entre les cultures cor\u00e9enne et fran\u00e7aise \u00e0 travers une programmation artistique et culturelle vari\u00e9e.<\/span><\/h3>\n<h3 class=\"ds-markdown-paragraph\"><strong><span>Expositions, spectacles, ateliers, rencontres, autant de rendez-vous pour d\u00e9couvrir la cr\u00e9ation contemporaine et traditionnelle cor\u00e9enne, et c\u00e9l\u00e9brer le dialogue entre nos deux pays.<\/span><\/strong><\/h3>\n<h3 class=\"ds-markdown-paragraph\"><strong><span>Toute l&rsquo;ann\u00e9e, en France et en Cor\u00e9e.<br \/><\/span><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<h4><em>La programmation compl\u00e8te sera d\u00e9voil\u00e9e progressivement.<\/em><\/h4>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_4,1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_delay=\u00a0\u00bb300ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEyMiJ9fQ==@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #C60C30;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: right;\"><a href=\"KFAC\" class=\"btn-read-more\">En savoir plus sur KFAC <span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>Le 27 juin 2026 &#8211; Epsedanse (Montpellier)<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>Workshop danse Kpop<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div>Cor\u00e9e&rsquo;Graphie est heureuse d&rsquo;accueillir \u00e0 nouveau <strong>Jay Kim<\/strong>, chor\u00e9graphe et professeur de renomm\u00e9e internationale, pour un workshop exceptionnel le <strong>27 juin 2026<\/strong> \u00e0 Montpellier.<\/div>\n<div>Originaire de S\u00e9oul et aujourd&rsquo;hui bas\u00e9 \u00e0 Londres, Jay Kim a \u00e9t\u00e9 professeur au c\u00e9l\u00e8bre studio <strong>1MILLION Dance Studio<\/strong> avant de poursuivre sa carri\u00e8re \u00e0 travers le monde. Il a travaill\u00e9 avec de nombreux artistes de la sc\u00e8ne K-Pop tels que <strong data-start=\"489\" data-end=\"501\">Jay Park<\/strong>, <stron>The Boyz ou encore <strong data-start=\"526\" data-end=\"535\">Luhan<\/strong>, et intervient r\u00e9guli\u00e8rement comme juge lors de comp\u00e9titions internationales, dont le <strong data-start=\"622\" data-end=\"646\">K-Pop World Festival<\/strong>. Il a d\u00e9j\u00e0 anim\u00e9 des workshops dans plus de 60 pays et pr\u00e8s de 170 villes \u00e0 travers le monde.<\/stron><\/div>\n<div aria-hidden=\"true\"><\/div>\n<div>Que vous soyez d\u00e9butant ou danseur confirm\u00e9, venez profiter d&rsquo;une occasion unique d&rsquo;apprendre directement aupr\u00e8s d&rsquo;un artiste reconnu pour son \u00e9nergie, sa p\u00e9dagogie et son expertise de la sc\u00e8ne K-Pop internationale.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div aria-hidden=\"true\"><\/div>\n<div>\ud83d\udcc5 <strong data-start=\"1000\" data-end=\"1023\">Samedi 27 juin 2026<\/strong><br \/>\ud83d\udccd <strong data-start=\"1029\" data-end=\"1056\">EPSEDANSE \u2013 <span data-olk-copy-source=\"MessageBody\">8, rue de Metz<\/span>\u00a0&#8211; Montpellier<\/strong><\/div>\n<div aria-hidden=\"true\"><\/div>\n<div>\ud83d\udcb6 <strong data-start=\"1061\" data-end=\"1073\">Tarifs :<\/strong><\/div>\n<div aria-hidden=\"true\"><\/div>\n<ul data-start=\"1074\" data-end=\"1166\">\n<li data-section-id=\"nwnin1\" data-start=\"1074\" data-end=\"1107\"><strong data-start=\"1076\" data-end=\"1084\">30 \u20ac<\/strong> pour les non-adh\u00e9rents<\/li>\n<li data-section-id=\"1o9220q\" data-start=\"1108\" data-end=\"1166\"><strong data-start=\"1110\" data-end=\"1118\">20 \u20ac<\/strong> pour les adh\u00e9rents <strong data-start=\"1138\" data-end=\"1155\">Cor\u00e9e&rsquo;Graphie<\/strong> et <strong data-start=\"1159\" data-end=\"1166\">KMF<\/strong><\/li>\n<\/ul>\n<div>\u26a0\ufe0f Les places sont limit\u00e9es. Ne manquez pas cette opportunit\u00e9 exceptionnelle de progresser, de vous challenger et de partager votre passion de la danse K-Pop avec l&rsquo;un des chor\u00e9graphes les plus reconnus de sa g\u00e9n\u00e9ration.<\/div>\n<div><\/div>\n<div><\/div>\n<div aria-hidden=\"true\"><\/div>\n<div><strong data-start=\"1390\" data-end=\"1418\">Inscription obligatoire.<\/strong><\/div>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||7px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9tZXRhX2tleSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIiwibWV0YV9rZXkiOiIifX0=@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/forms.gle\/Gg9raswDAPXQbiPP9\" class=\"btn-read-more\">Inscription<span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/06\/JAY-KIM-poster-1.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text=\u00a0\u00bbJAY-KIM-poster\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<strong><em>Le 10 Mai &#8211; Bar Le Clandestin (Montpellier)<\/em><\/strong>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Karaok\u00e9 Kpop<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Concours Karaok\u00e9 K-pop \u00e0 Montpellier<\/strong><\/p>\n<p>Le <strong>dimanche 10 mai 2026<\/strong>, l\u2019association <strong>Cor\u00e9e\u2019Graphie<\/strong> organise un <strong>concours de karaok\u00e9 K-pop<\/strong> au <strong>Bar Le Clandestin<\/strong>, \u00e0 Montpellier.<\/p>\n<p>L\u2019\u00e9v\u00e9nement est ouvert aux amateurs de K-pop souhaitant participer, chanter, partager un moment convivial et tenter de remporter l\u2019un des <strong>3 prix \u00e0 gagner<\/strong>.<\/p>\n<p>Des <strong>goodies seront offerts \u00e0 tous les participants<\/strong>. Des <strong>snacks et boissons cor\u00e9ennes<\/strong> seront \u00e9galement propos\u00e9s sur place.<\/p>\n<p><strong>Lieu<\/strong><br \/>Bar Le Clandestin<br \/>Montpellier<\/p>\n<p><strong>Tarifs<\/strong><br \/>5 \u20ac par personne<br \/>3 \u20ac pour les adh\u00e9rents<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||7px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9tZXRhX2tleSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIiwibWV0YV9rZXkiOiIifX0=@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.helloasso.com\/associations\/coree-graphie\/evenements\/concours-karaoke-kpop\" class=\"btn-read-more\">Inscription<span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/05\/concours-karaoke-kpop.jpg\u00a0\u00bb alt=\u00a0\u00bbKaraok\u00e9 Kpop &#8211; 10 Mai &#8211; Bar Le Clandestin (Montpellier)\u00a0\u00bb title_text=\u00a0\u00bbconcours-karaoke-kpop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>Le 17 Mai &#8211; Salle La Fourguette (Toulouse)<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>K-Pop World Festival 2026<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af\" style=\"--x---base-line-clamp-line-height: 18px; --x-lineheight: 18px;\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x126k92a\" style=\"line-height: 18px;\">Le <strong>K-Pop World Festival 2026<\/strong> d\u00e9barque \u00e0 Toulouse avec une s\u00e9lection officielle ouverte aux meilleurs crews du sud de la France.<\/p>\n<p>\ud83d\udccd Demi-finale \u2013 17 mai 2026<br \/>Salle La Fourguette (Toulouse)<br \/>Une \u00e9tape d\u00e9cisive pour tenter de repr\u00e9senter la France en Cor\u00e9e du Sud.<\/p>\n<p>\u2e3b<\/p>\n<p>\ud83d\ude80 Inscriptions ouvertes<\/p>\n<p>\ud83d\udc65 2 \u00e0 5 danseurs (16 ans minimum)<br \/>\ud83c\udfb5 1 performance K-Pop (max. 4 minutes)<br \/>\ud83d\udce9 S\u00e9lection sur vid\u00e9o (40 secondes)<\/p>\n<p>Tu penses avoir le niveau ?<br \/>Forme ton crew et tente ta chance !<\/p>\n<p>\ud83d\udc49 Infos pratiques kworldfestivalmontpellier@gmail.com<\/span><\/span><\/p>\n<p><strong>Date<\/strong><br \/>Dimanche 17 mai 2026<\/p>\n<p><strong>Lieu<\/strong><br \/>Salle La Fourguette<br \/>Toulouse<strong><a href=\"http:\/\/www.coree-graphie.com\"><\/a><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/05\/kworld-affiche.jpg\u00a0\u00bb alt=\u00a0\u00bbK-World 2026 &#8211; 17 Mai &#8211; Salle La Fourguette (Toulouse)\u00a0\u00bb title_text=\u00a0\u00bbkworld-affiche\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<strong><em>Le 23 mai 2026 &#8211; MBA34 (Montpellier)<\/em><\/strong>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Workshop MOVE &amp; CONNECT &#8211; Mo&rsquo;Nello<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"isSelectedEnd\"><strong><span>Workshop K-pop \/ Popping avec Mo\u2019nello \u00e0 Montpellier<\/span><\/strong><\/p>\n<p class=\"isSelectedEnd\"><span>Dans le cadre de la tourn\u00e9e <\/span><strong><span>Move &amp; Connect<\/span><\/strong><span>, le danseur <\/span><strong><span>Mo\u2019nello<\/span><\/strong><span> animera un workshop de danse \u00e0 Montpellier le <\/span><strong><span>samedi 23 mai 2026<\/span><\/strong><span>, autour de la K-pop et du popping.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Deux s\u00e9ances sont propos\u00e9es au cours de la journ\u00e9e :<\/span><\/p>\n<p class=\"isSelectedEnd\"><strong><span>10h30 \u00e0 12h00<\/span><\/strong><br \/><span>Chor\u00e9graphie originale, avec bases de popping<\/span><\/p>\n<p class=\"isSelectedEnd\"><strong><span>14h00 \u00e0 15h30<\/span><\/strong><br \/><span>Chor\u00e9graphie originale, style K-pop<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Le workshop est ouvert \u00e0 partir de <\/span><strong><span>15 ans<\/span><\/strong><span>. Les places sont limit\u00e9es.<\/span><\/p>\n<p><strong><span>Lieu<\/span><\/strong><br \/><span>MBA34<\/span><br \/><span>59 rue de l\u2019Industrie<\/span><br \/><span>34070 Montpellier<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||7px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9tZXRhX2tleSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIiwibWV0YV9rZXkiOiIifX0=@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/forms.gle\/UnJwXL7XJqcSFaHr5\" class=\"btn-read-more\">Inscription<span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/05\/monello-affiche.jpg\u00a0\u00bb alt=\u00a0\u00bbWorkshop MOVE &#038; CONNECT &#8211; Mo&rsquo;Nello\u00a0\u00bb title_text=\u00a0\u00bbmonello-affiche\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<strong><em>Du 20 au 30 avril 2026 \u00e0 la maison pour tous Frida Kahlo  (Montpellier)<\/em><\/strong>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Visa pour la Cor\u00e9e<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Visa pour la Cor\u00e9e<\/h2>\n<p><b>Du 20 au 30 avril<\/b><\/p>\n<p>Dans le cadre de <b>Visa pour la Cor\u00e9e<\/b>, plusieurs ateliers sont propos\u00e9s autour de la culture cor\u00e9enne : arts traditionnels, cuisine, culture K-Pop et danse. Ces rendez-vous permettent de d\u00e9couvrir diff\u00e9rentes pratiques culturelles cor\u00e9ennes \u00e0 travers des formats accessibles, cr\u00e9atifs et participatifs.<\/p>\n<p>Les activit\u00e9s sont organis\u00e9es avec diff\u00e9rents partenaires, notamment l\u2019association <b>Cor\u00e9e\u2019graphie<\/b> et <b>KPOP Montpellier France<\/b>.<\/p>\n<hr style=\"width: 80px; margin: 24px 0; border: 0; border-top: 2px solid currentColor;\" \/>\n<h3>Programme<\/h3>\n<p><b>Fabrication de cartes traditionnelles<\/b><br \/><i>Atelier cr\u00e9atif<\/i><br \/>Lundi 20 avril, de 14h30 \u00e0 16h30 \/ Avec Kim Young Hee<br \/>Cet atelier propose de d\u00e9couvrir le papier traditionnel cor\u00e9en, appel\u00e9 <b>Hanji<\/b>, puis de r\u00e9aliser de petites cartes d\u00e9coratives \u00e0 partir de techniques simples de pliage et d\u2019ornement. Les cr\u00e9ations pourront \u00eatre utilis\u00e9es comme cartes de v\u0153ux, souvenirs ou petits objets \u00e0 offrir.<br \/><b>Public :<\/b> \u00e0 partir de 8 ans<br \/><b>Tarif :<\/b> 4 \u20ac + carte MPT<br \/><b>R\u00e9servation :<\/b> 04 48 18 62 17<br \/><b>Inscriptions :<\/b> \u00e0 partir du 23 mars<\/p>\n<hr style=\"width: 80px; margin: 24px 0; border: 0; border-top: 2px solid currentColor;\" \/>\n<p><b>Atelier peinture d\u2019\u00e9ventail cor\u00e9en<\/b><\/p>\n<p><i>Atelier cr\u00e9atif<\/i><br \/>Mardi 21 avril, de 14h30 \u00e0 16h30 \/ Avec Kim Young Hee<br \/>Les participants d\u00e9couvriront l\u2019univers des \u00e9ventails traditionnels cor\u00e9ens, appel\u00e9s <b>buchae<\/b>, avant de peindre et d\u00e9corer leur propre \u00e9ventail. L\u2019atelier m\u00eale approche artistique, motifs inspir\u00e9s de la culture cor\u00e9enne et cr\u00e9ation personnelle.<br \/><b>Public :<\/b> \u00e0 partir de 8 ans<br \/><b>Tarif :<\/b> 4 \u20ac + carte MPT<br \/><b>R\u00e9servation :<\/b> 04 48 18 62 17<br \/><b>Inscriptions :<\/b> \u00e0 partir du 23 mars<\/p>\n<hr style=\"width: 80px; margin: 24px 0; border: 0; border-top: 2px solid currentColor;\" \/>\n<p><b>Cuisine cor\u00e9enne : Jumeobap &amp; Tteokbokki<\/b><\/p>\n<p><i>Atelier culinaire<\/i><br \/>Mercredi 22 avril, de 14h30 \u00e0 16h30 \/ Avec Kim Young Hee<br \/>Un atelier culinaire autour de deux sp\u00e9cialit\u00e9s populaires cor\u00e9ennes : le <b>Jumeobap<\/b>, boulette de riz fa\u00e7onn\u00e9e \u00e0 la main, et le <b>Tteokbokki<\/b>, plat de street-food embl\u00e9matique \u00e0 base de g\u00e2teaux de riz. Une version douce sera propos\u00e9e afin de permettre \u00e0 tous de participer et de go\u00fbter cette sp\u00e9cialit\u00e9.<br \/><b>Public :<\/b> \u00e0 partir de 10 ans<br \/><b>Tarif :<\/b> 4 \u20ac + carte Maison pour tous<br \/><b>R\u00e9servation :<\/b> 04 48 18 62 17<br \/><b>Inscriptions :<\/b> \u00e0 partir du 23 mars<\/p>\n<hr style=\"width: 80px; margin: 24px 0; border: 0; border-top: 2px solid currentColor;\" \/>\n<p><b>K-Pop Culture<\/b><\/p>\n<p><i>Matin\u00e9e ludique<\/i><br \/>Mercredi 29 avril, de 10h \u00e0 12h<br \/>Une matin\u00e9e ludique autour de l\u2019univers de la K-Pop et de la culture pop cor\u00e9enne. Au programme : quiz, jeux de soci\u00e9t\u00e9, coloriage th\u00e9matique et blind test musical. Un moment convivial pour d\u00e9couvrir ou red\u00e9couvrir la K-Pop en s\u2019amusant.<br \/><b>Public :<\/b> \u00e0 partir de 8 ans<br \/><b>Tarif :<\/b> 4 \u20ac + carte Maison pour tous<br \/><b>R\u00e9servation :<\/b> 04 48 18 62 17<br \/><b>Inscriptions :<\/b> \u00e0 partir du 23 mars<\/p>\n<hr style=\"width: 80px; margin: 24px 0; border: 0; border-top: 2px solid currentColor;\" \/>\n<p><b>Workshop de danse K-Pop<\/b><br \/><i>Danse K-Pop<\/i><br \/>Du 28 au 30 avril, de 15h \u00e0 16h30 \/ Avec Kim Suhwa<br \/>Ce stage intensif propose aux adolescents de d\u00e9couvrir l\u2019univers de la danse K-Pop \u00e0 travers l\u2019apprentissage d\u2019une chor\u00e9graphie inspir\u00e9e des studios de danse en Cor\u00e9e. Le workshop permettra de travailler la coordination, le rythme, l\u2019\u00e9nergie et le style propre \u00e0 cette esth\u00e9tique tr\u00e8s populaire.<br \/>\u00c0 l\u2019issue du stage, les participants pourront filmer la chor\u00e9graphie apprise afin de garder une trace de cette exp\u00e9rience.<br \/><b>Public :<\/b> de 12 \u00e0 16 ans<br \/><b>Tarif :<\/b> 9 \u20ac + carte Maison pour tous<br \/><b>R\u00e9servation :<\/b> 04 48 18 62 17<br \/><b>Inscriptions :<\/b> \u00e0 partir du 23 mars<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/05\/visa-pour-la-coree.jpg\u00a0\u00bb alt=\u00a0\u00bbWorkshop MOVE &#038; CONNECT &#8211; Mo&rsquo;Nello\u00a0\u00bb title_text=\u00a0\u00bbvisa-pour-la-cor\u00e9e\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>Le jeudi 26 mars 2026 \u00e0 19h au Centre Culturel Cor\u00e9en \/ Paris<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb33px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Rencontre-performance avec la v\u00e9n\u00e9rable Ju Seok, po\u00e9tesse<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"ds-markdown-paragraph\"><span>Dans le cadre du Printemps des Po\u00e8tes, manifestation nationale d\u00e9di\u00e9e \u00e0 la po\u00e9sie soutenue par le Centre national du livre, le Centre Culturel Cor\u00e9en accueille <strong>Ju Seok<\/strong>, religieuse bouddhiste et po\u00e9tesse, pour une soir\u00e9e exceptionnelle m\u00ealant po\u00e9sie, danse et musique.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span>Cet \u00e9v\u00e9nement s&rsquo;inscrit dans les c\u00e9l\u00e9brations des <\/span><strong><span>140 ans des relations diplomatiques entre la France et la Cor\u00e9e<\/span><\/strong><span>, et a \u00e9t\u00e9 retenu par l&rsquo;ambassade de Cor\u00e9e en France comme projet comm\u00e9moratif officiel dans le cadre du programme <\/span><em><span>Korean French Art Connections (KFAC)<\/span><\/em><span>.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span>\u00c0 l&rsquo;occasion de la parution en \u00e9dition bilingue de son recueil <\/span><em><span>Vous \u00eates le centre de ce jour<\/span><\/em><span> (<\/span><em><span>\uadf8\ub300\uac00 \uc624\ub298\uc758 \uc911\uc2ec\uc785\ub2c8\ub2e4<\/span><\/em><span>), publi\u00e9 simultan\u00e9ment aux \u00e9ditions Racine (Paris) et Dham&amp;Books (S\u00e9oul), Ju Seok <\/span><span>pr\u00e9sentera son \u0153uvre et son parcours.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span>La soir\u00e9e d\u00e9butera par une lecture bilingue de ses po\u00e8mes assur\u00e9e par le po\u00e8te et traducteur <strong>Moon Younghoon<\/strong>. <br \/>Elle prendra ensuite la forme d&rsquo;une performance graphique : l&rsquo;autrice r\u00e9alisera en direct des dessins spontan\u00e9s \u00e0 l&rsquo;encre noire, accompagn\u00e9e de danses contemporaines chor\u00e9graphi\u00e9es par <strong>Nam Young-ho<\/strong> et interpr\u00e9t\u00e9es par des artistes franco-cor\u00e9ens, pour un moment sensible et immersif \u00e0 la crois\u00e9e des arts.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span>Une s\u00e9ance de d\u00e9dicaces et un moment de convivialit\u00e9 permettront au public d&rsquo;\u00e9changer avec l&rsquo;artiste \u00e0 l&rsquo;issue de la performance.<\/span><!--<\/p>\n\n\n\n<p>Le Suyeong Yaryu a lieu lors de la pleine lune du Nouvel An lunaire cor\u00e9en.<\/p>\n\n\n\n<p>Il se compose de 4 sections repr\u00e9sentant chacune une \u00e9motion propre \u00e0 la perception cor\u00e9enne de la vie et mettant en lumi\u00e8re diff\u00e9rentes th\u00e9matiques :<\/p>\n\n\n\n<p>\u2022 <strong>Yangban<\/strong> (classe aristocratique traditionnelle cor\u00e9enne) : cette mise en sc\u00e8ne repr\u00e9sente 5 aristocrates incomp\u00e9tents et pr\u00e9tentieux sujet \u00e0 des moqueries et des insultes de la part d'un fermier de la classe inf\u00e9rieure. Elle illustre les probl\u00e8mes de la soci\u00e9t\u00e9 de classes cor\u00e9enne.<\/p>\n\n\n\n<p>\u2022 <strong>Yeongno<\/strong> (b\u00eate fantastique associ\u00e9e \u00e0 l'au-del\u00e0 ): cette partie r\u00e9v\u00e8le le fort sentiment de r\u00e9sistance du peuple face \u00e0 la classe sup\u00e9rieure \u00e0 travers la punition exerc\u00e9e par Yeongno. Elle illustre la contradiction entre la vie et la mort<\/p>\n\n\n\n<p>\u2022 <strong>La grand-m\u00e8re et le grand-p\u00e8re<\/strong> : cette partie illustre un couple o\u00f9 le grand-p\u00e8re tombe sous le charme d'une jeune concubine lors<\/p>\n\n\n\n<p>de son \u00e9veil, causant la mort de sa partenaire. Il finit par perdre la raison en raison de sa culpabilit\u00e9. Le comportement de la grand-m\u00e8re cherche \u00e0 amener la r\u00e9flexion sur la mani\u00e8re dont la vie des gens ordinaires est per\u00e7ue face \u00e0 la r\u00e9alit\u00e9. Elle illustre la relation femme\/homme.<\/p>\n\n\n\n<p>\u2022 <strong>Le lion<\/strong> : cette derni\u00e8re partie met en sc\u00e8ne un pantomime o\u00f9 un lion et un tigre dansent et se battent. Elle se termine par la victoire du lion sur le tigre. Elle met en avant l'id\u00e9ologie cor\u00e9enne de surmonter la peur.--><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||7px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9tZXRhX2tleSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIiwibWV0YV9rZXkiOiIifX0=@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>Le jeudi 26 mars 2026 \u00e0 19h au Centre Culturel Cor\u00e9en \/ Paris<\/em><\/strong><\/p>\n<p>Entr\u00e9e libre sur r\u00e9servation<\/p>\n<p style=\"text-align: left;\"><a href=\"ju-seok\" class=\"btn-read-more\">Toutes les informations <span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2026\/03\/ju-seok.jpg\u00a0\u00bb alt=\u00a0\u00bbJu Seok\u00a0\u00bb title_text=\u00a0\u00bbju-seok\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb specialty=\u00a0\u00bbon\u00a0\u00bb parallax_2=\u00a0\u00bbon\u00a0\u00bb bg_img_2=\u00a0\u00bbhttp:\/\/kfac.fr\/wp-content\/uploads\/2025\/05\/Suyeong-Yaryu-4.png\u00a0\u00bb padding_top_1=\u00a0\u00bb0px\u00a0\u00bb padding_bottom_1=\u00a0\u00bb0px\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbtrue\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_1_tablet=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb padding_1_phone=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb padding_1_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbFeatures\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#003478&Prime; background_image=\u00a0\u00bbhttp:\/\/kfac.fr\/wp-content\/uploads\/2025\/05\/Suyeong-Yaryu-1.png\u00a0\u00bb background_blend=\u00a0\u00bbsaturation\u00a0\u00bb inner_max_width=\u00a0\u00bb2000px\u00a0\u00bb min_height=\u00a0\u00bb500px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb100px||100px||true|false\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|0px|false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#E02B20&Prime; header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb400ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>LE SAMEDI 11 OCTOBRE 2025 \u00e0 19h \/ Op\u00e9ra Com\u00e9die \/ Salle Moli\u00e8re \/ Montpellier<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb55px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb750ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Suyeong Yaryu<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Le Suyeong Yaryu est une pi\u00e8ce de th\u00e9\u00e2tre traditionnel qui se joue avec un masque, originaire des villes de Suyeong-dong, Nam-du et Busan.<\/p>\n<p>Il est consid\u00e9r\u00e9 comme un bien culturel immat\u00e9riel depuis 1971. Il s&rsquo;agit d&rsquo;un rite social et artistique, comprenant un jeu d&rsquo;acteurs, de la danse et de la musique. De nos jours, il existe un centre de formation \u00e0 Suyeong-dong au sein du parc Suyeong.<br \/>\nLe nom \u00ab\u00a0Yaryu (Deulnori), pi\u00e8ce champ\u00eatre\u00a0\u00bb est d\u00fb au fait que la pi\u00e8ce se joue en ext\u00e9rieur dans un grand champ. Le Suyeong Yaryu a lieu lors de la pleine lune du Nouvel An lunaire cor\u00e9en. Il se compose de 4 sections.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tarif : 10\u20ac + 1 place offerte<br \/>Dur\u00e9e du spectacle : 1h<\/em>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE0MyJ9fQ==@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: right;\"><a href=\"suyeong-yaryu\/\" class=\"btn-read-more\">Toutes les informations <span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height_tablet=\u00a0\u00bb50vw\u00a0\u00bb height_phone=\u00a0\u00bb50vw\u00a0\u00bb height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80vw\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb55px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb700ms\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb38px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><em>L<span style=\"font-weight: bold; font-size: 1.1em;\">e 14 octobre 2025 : d\u00eener cor\u00e9en au restaurant du lyc\u00e9e h\u00f4telier Georges Fr\u00eache <\/span><\/em><\/strong><\/p>\n<h2><span style=\"font-weight: bold; font-size: 1em;\"><i>D\u00e9couverte de la gastronomie Cor\u00e9enne<\/i><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Nous vous proposons de d\u00e9couvrir les richesses de la gastronomie cor\u00e9enne \u00e0 l\u2019occasion d\u2019un d\u00eener exceptionnel au lyc\u00e9e h\u00f4telier Georges Fr\u00eache concoct\u00e9 par le chef cor\u00e9en Choi-Jae-hyun assist\u00e9 de Shin-Min-gyu.<\/p>\n<p><strong data-start=\"120\" data-end=\"167\">Choi Jae-hyun \u2013 Pr\u00e9sident de Taeyang Global<\/strong><br data-start=\"167\" data-end=\"170\" \/>Ancien membre du d\u00e9partement restauration du Seoul Plaza Hotel (1988\u20112024). Responsable g\u00e9n\u00e9ral de multiples \u00e9v\u00e9nements internationaux de gastronomie cor\u00e9enne (Sri Lanka, Italie, Malaisie, Luxembourg, France) et membre du conseil d\u2019administration de l\u2019Association des Arts Traditionnels, branche Gyeonggi.<\/p>\n<p data-start=\"479\" data-end=\"878\">Vision personnelle :<br data-start=\"501\" data-end=\"504\" \/><em>Avec la voix de notre peuple et la danse de nos traditions, je souhaite contribuer \u00e0 cr\u00e9er un monde empreint de vitalit\u00e9.<\/em><br data-start=\"625\" data-end=\"628\" \/><em>Par l\u2019apprentissage et la pratique de la cuisine cor\u00e9enne, du b\u00e9n\u00e9volat, de la randonn\u00e9e et du samulnori (percussions traditionnelles), je m\u2019efforce, \u00e0 travers les \u00e9v\u00e9nements d\u2019\u00e9changes internationaux, de faire rayonner notre culture dans le monde.<\/em><\/p>\n<p data-start=\"112\" data-end=\"511\"><strong data-start=\"112\" data-end=\"169\">Shin Min-gyu \u2013 Chef ex\u00e9cutif, H\u00f4tel The Plaza (S\u00e9oul)<\/strong><br data-start=\"169\" data-end=\"172\" \/>30 ans d\u2019exp\u00e9rience en cuisine et gestion h\u00f4teli\u00e8re, avec un parcours allant de la cuisine occidentale \u00e0 la direction culinaire et aux achats, incluant formations et interventions internationales (CJ Cooking Academy, Marriott, festivals en France et Luxembourg). Certifi\u00e9 en cuisine cor\u00e9enne et occidentale, hygi\u00e8ne alimentaire et HACCP.<\/p>\n<p data-start=\"513\" data-end=\"756\">Philosophie culinaire<br data-start=\"538\" data-end=\"541\" \/><em>La sinc\u00e9rit\u00e9 est le meilleur assaisonnement, et la force d\u2019un repas peut transformer toute une journ\u00e9e.<\/em><br data-start=\"648\" data-end=\"651\" \/><em>Je consid\u00e8re que la cuisine n\u2019est pas un simple repas, mais un art capable de toucher le c\u0153ur des gens.<\/em><\/p>\n<p><strong>Au menu :<\/strong> vermicelles de patate douce saut\u00e9s au b\u0153uf, porc \u00e9pic\u00e9 saut\u00e9, namul de l\u00e9gumes de montagne assaisonn\u00e9s, \u0153ufs de colin sal\u00e9s, courgettes saut\u00e9es aux crevettes sal\u00e9es, pancake cor\u00e9en sal\u00e9, soupe de p\u00e2te de soja, kimchi frais non ferment\u00e9, riz blanc, fruits.<\/p>\n<p>Le 14 octobre \u00e0 partir de 19h.<br \/><i>30 personnes maximum<\/i><br \/>R\u00e9servations aupr\u00e8s du restaurant : 04 67 13 05 05<\/p>\n<p>Adresse : lyc\u00e9e h\u00f4telier Georges Fr\u00eache, 401 Rue Le Titien, 34000 Montpellier<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/10\/chefs-oct25.jpg\u00a0\u00bb title_text=\u00a0\u00bbchefs-oct25&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/10\/gastro-freche.jpg\u00a0\u00bb title_text=\u00a0\u00bbgastro-freche\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#cd2e3a\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb80vw\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb400ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<strong><em>Les 9, 10, 13 &#038; 14 OCTOBRE 2025 dans cinq \u00e9tablissements scolaires de l&rsquo;agglom\u00e9ration de Montpellier<\/em><\/strong>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb55px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb750ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Journ\u00e9es de la Cor\u00e9e<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>KFAC propose une journ\u00e9e de la Cor\u00e9e dans quatre \u00e9tablissements scolaires de l&rsquo;agglom\u00e9ration de Montpellier.<\/p>\n<p>Au programme : spectacles de danse traditionnelle cor\u00e9enne, ateliers cr\u00e9atifs et exp\u00e9riences culinaires vari\u00e9es.<\/p>\n<ul>\n<li class=\"whitespace-normal break-words\">9 octobre : Lyc\u00e9e Jules Guesde<\/li>\n<li class=\"whitespace-normal break-words\">10 octobre : Coll\u00e8ge Arthur Rimbaud<\/li>\n<li class=\"whitespace-normal break-words\">13 octobre : Lyc\u00e9e <span data-olk-copy-source=\"MessageBody\">Dhuoda<\/span> et Coll\u00e8ge Fontcarrade<\/li>\n<li class=\"whitespace-normal break-words\">14 octobre : Lyc\u00e9e Jean Monnet<\/li>\n<\/ul>\n<p><i>En partenariat avec le centre culturel Cor\u00e9en, Montpellier M\u00e9diterran\u00e9e M\u00e9tropole, et l&rsquo;acad\u00e9mie de Montpellier<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/09\/journee-de-la-coree.jpg\u00a0\u00bb alt=\u00a0\u00bbJourn\u00e9es de la Cor\u00e9e\u00a0\u00bb title_text=\u00a0\u00bbjournee-de-la-coree\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_height=\u00a0\u00bb76vh\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb specialty=\u00a0\u00bbon\u00a0\u00bb parallax_2=\u00a0\u00bbon\u00a0\u00bb bg_img_2=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/06\/Poester-Image2.jpg\u00a0\u00bb padding_top_1=\u00a0\u00bb0px\u00a0\u00bb padding_bottom_1=\u00a0\u00bb0px\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbtrue\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_1_tablet=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb padding_1_phone=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb padding_1_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbFeatures\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb inner_max_width=\u00a0\u00bb2000px\u00a0\u00bb min_height=\u00a0\u00bb500px\u00a0\u00bb custom_margin=\u00a0\u00bb25px||25px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|0px|false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#003478&Prime; text_font_size=\u00a0\u00bb21px\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_2_text_color=\u00a0\u00bb#0C71C3&Prime; header_3_font_size=\u00a0\u00bb25px\u00a0\u00bb custom_margin=\u00a0\u00bb||0px|||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb400ms\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb21px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb12px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><em>Proposition \u00e0 l&rsquo;occasion des 25 ans de la Maison des relations internationales Nelson Mandela de Montpellier<\/em><\/h3>\n<p><strong><em>Les 23 &amp; 24 juin 2025<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb94348bfe-9160-40f2-a5f0-d862bcd89ff1&Prime; header_2_font_size=\u00a0\u00bb55px\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb700ms\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb38px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>S\u00e9oul Gyobang<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbfb1c5645-9bde-45e1-8467-0687ce78b789&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>S\u00e9oul Gyobang, fond\u00e9e en 2010 par la directrice artistique Kim Kyung-ran, est une compagnie d\u00e9di\u00e9e \u00e0 la pr\u00e9servation et au d\u00e9veloppement de l&rsquo;art chor\u00e9graphique traditionnel cor\u00e9en. Cette troupe a pour mission de r\u00e9interpr\u00e9ter les danses du &lsquo;Gwonbeon&rsquo; \u2014 institution de formation des artistes f\u00e9minines de l&rsquo;\u00e8re moderne cor\u00e9enne \u2014 \u00e0 travers une esth\u00e9tique contemporaine, afin d&rsquo;en transmettre l&rsquo;essence vivante au public actuel.<\/p>\n<p><strong><em>\u2018S\u00e9r\u00e9nade de danse cor\u00e9enne\u2019<\/em><\/strong> est un spectacle compos\u00e9 de cinq pi\u00e8ces s\u00e9lectionn\u00e9es dans le r\u00e9pertoire de S\u00e9oul Gyobang, incarnant avec harmonie l&rsquo;\u00e9l\u00e9gance \u00e9pur\u00e9e et l&rsquo;\u00e9nergie dynamique propre \u00e0 la danse traditionnelle cor\u00e9enne.<\/p>\n<p>Pour cette repr\u00e9sentation \u00e0 Montpellier, six des plus \u00e9minentes danseuses de la compagnie monteront sur sc\u00e8ne pour r\u00e9v\u00e9ler la quintessence de l&rsquo;art traditionnel cor\u00e9en.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2OSJ9fQ==@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: right;\"><a href=\"seoul-gyobang\/\" class=\"btn-read-more\">Toutes les informations <span class=\"arrow\">\u2794<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height_tablet=\u00a0\u00bb50vw\u00a0\u00bb height_phone=\u00a0\u00bb50vw\u00a0\u00bb height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-6px||||false|false\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/youtu.be\/8l6YGD8aA0M\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<hr style=\"width: 60%; margin: 10px auto; border: none; border-top: 1px solid #444;\" \/>\n<h3 style=\"margin: 20px 0px; text-align: center;\">Les 23 &amp; 24 juin 2025, nous vous proposons deux rendez-vous avec S\u00e9oul Gyobang<\/h3>\n<hr style=\"width: 60%; margin: 10px auto; border: none; border-top: 1px solid #444;\" \/>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1200px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb500ms\u00a0\u00bb border_radii=\u00a0\u00bbon|7px|7px|7px|7px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb custom_margin=\u00a0\u00bb13px||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb500ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">S<em><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">pectacle de danse traditionnelle<\/span><\/em><em><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><\/span><\/em><\/h3>\n<h2 style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>S\u00e9r\u00e9nade de danse cor\u00e9enne<\/strong><\/span><\/h2>\n<h3 style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>&#8211; version compl\u00e8te &#8211;<\/strong><\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb1em\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||16px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong><em>Le lundi 23 juin 2025 \u00e0 20h \u00e0 l&rsquo;op\u00e9ra Com\u00e9die de Montpellier \/ Salle Moli\u00e8re<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em><\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/05\/Dokgong-Dokmu-Seoul-Gyobang.jpg\u00a0\u00bb alt=\u00a0\u00bbDokgong Dokmu Seoul Gyobang\u00a0\u00bb title_text=\u00a0\u00bbDokgong-Dokmu-Seoul-Gyobang\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2OSJ9fQ==@\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb2px|5px||5px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Projet embl\u00e9matique de S\u00e9oul Gyobang, <strong><em>\u2018S\u00e9r\u00e9nade de danse cor\u00e9enne\u2019<\/em><\/strong> est une performance dans\u00e9e autour de chor\u00e9graphies transmises et r\u00e9interpr\u00e9t\u00e9es par Kim Kyung-ran.<br data-start=\"244\" data-end=\"247\" \/>Le spectacle est compos\u00e9 de cinq pi\u00e8ces s\u00e9lectionn\u00e9es dans le r\u00e9pertoire de la compagnie, incarnant avec harmonie l&rsquo;\u00e9l\u00e9gance \u00e9pur\u00e9e et l&rsquo;\u00e9nergie dynamique propre \u00e0 la danse traditionnelle cor\u00e9enne.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb|12px|0px|12px|false|true\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Dur\u00e9e : 1h<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Gratuit sur r\u00e9servation<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bblink_option_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||7px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb650ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb44%\u00a0\u00bb link_option_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9tZXRhX2tleSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIiwibWV0YV9rZXkiOiIifX0=@\u00a0\u00bb custom_css_free_form=\u00a0\u00bb.btn-read-more {||  display: inline-flex;||  align-items: center;||  padding: 0.6em 1.2em;||  background: #000000;       \/* fond noir *\/||  color: white;||  font-weight: 600;||  border-radius: 4px;        \/* bordure tr\u00e8s peu arrondie *\/||  border: 2px solid white;   \/* bordure blanche *\/||  text-decoration: none;||  font-family: &lsquo;Segoe UI&rsquo;, Tahoma, Geneva, Verdana, sans-serif;||  transition: background-color 0.3s ease, color 0.3s ease;||  cursor: pointer;||  user-select: none;||  box-shadow: none;||}||||.btn-read-more .arrow {||  display: inline-block;||  margin-left: 0.5em;||  font-weight: 700;||  transition: transform 0.3s ease;||  font-size:1.3em;||}||||.btn-read-more:hover {||  background: white;        \/* fond blanc au hover *\/||  color: black;             \/* texte noir au hover *\/||  border-color: black;      \/* bordure noire au hover *\/||}||||.btn-read-more:hover .arrow {||  transform: translateX(6px);||  color: black;||}||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.helloasso.com\/associations\/coree-graphie\/evenements\/spectacle-seoul-gyobang\" class=\"btn-read-more\" target=\"_blank\" rel=\"noopener\" title=\"R\u00e9servation\">R\u00e9servation \u2794<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_duration=\u00a0\u00bb500ms\u00a0\u00bb border_radii=\u00a0\u00bbon|7px|7px|7px|7px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb custom_margin=\u00a0\u00bb13px||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb500ms\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">S<em><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">pectacle de danse traditionnelle<\/span><\/em><em><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><\/span><\/em><\/h3>\n<h2 style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>S\u00e9r\u00e9nade de danse cor\u00e9enne<\/strong><\/span><\/h2>\n<h3 style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>&#8211; s\u00e9lection &#8211;<\/strong><\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb1em\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||16px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong><em>Le mardi 24 juin 2025 \u00e0 16h \u00e0 la maison des relations internationales Nelson Mandela de Montpellier<br \/><\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/kfac.fr\/wp-content\/uploads\/2025\/06\/mri-show2.jpg\u00a0\u00bb alt=\u00a0\u00bbSeoul Gyobang\u00a0\u00bb title_text=\u00a0\u00bbmri-show2&Prime; url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE2OSJ9fQ==@\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb2px|5px||5px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p data-start=\"93\" data-end=\"250\">\u00c0 l\u2019occasion de cette repr\u00e9sentation, une s\u00e9lection de trois danses est propos\u00e9e : <em data-start=\"178\" data-end=\"203\">Janggu Dance \u2013 Unbinami<\/em>, <em data-start=\"205\" data-end=\"221\">Minsalpurichum<\/em> et <em data-start=\"225\" data-end=\"247\">Gyobang Gutgeorichum<\/em>.<\/p>\n<p data-start=\"252\" data-end=\"347\">Chaque danseuse y d\u00e9voile un univers singulier \u00e0 travers une cr\u00e9ation chor\u00e9graphique originale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_margin=\u00a0\u00bb|12px|4px|12px|false|true\u00a0\u00bb custom_padding=\u00a0\u00bb||3px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Dur\u00e9e : 30mn<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Entr\u00e9e libre &amp; gratuite<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbContact Form\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb900px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bba4f60ef7-2627-4517-8ba4-ab233b149ad3&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Newsletter<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<iframe data-w-type=\"embedded\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"https:\/\/458v.mj.am\/wgt\/458v\/q33\/form?c=f7b4f023\" width=\"100%\" style=\"height: 0;\"><\/iframe><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\" src=\"https:\/\/app.mailjet.com\/pas-nc-embedded-v1.js\"><\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbFooter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bbnone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttp:\/\/kfac.fr\/wp-content\/uploads\/2025\/05\/logo-kfac-h70-white.png\u00a0\u00bb alt=\u00a0\u00bbKorean French Art Connexion\u00a0\u00bb title_text=\u00a0\u00bblogo-kfac-h70-white\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybCIsInNldHRpbmdzIjp7fX0=@\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_social_media_follow _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbright\u00a0\u00bb text_orientation_tablet=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_phone=\u00a0\u00bbcenter\u00a0\u00bb text_orientation_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_social_media_follow_network social_network=\u00a0\u00bbfacebook\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.facebook.com\/festivalcoreedici\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbinstagram\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.instagram.com\/association_coreegraphie\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbtiktok\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.tiktok.com\/@coreegraphie\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_enable_color=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]tiktok[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbyoutube\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.youtube.com\/channel\/UCqpPGDrDt0USoG3pQdcu7PQ\/videos\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_enable_color=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>korean french art connectionKOREAN FRENCH ART CONNECTION 2026Apr\u00e8s une premi\u00e8re ann\u00e9e riche en \u00e9changes, Korean French Art Connection poursuit sa mission en 2026 : cr\u00e9er des passerelles entre les cultures cor\u00e9enne et fran\u00e7aise \u00e0 travers une programmation artistique et culturelle vari\u00e9e. Expositions, spectacles, ateliers, rencontres, autant de rendez-vous pour d\u00e9couvrir la cr\u00e9ation contemporaine et traditionnelle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":156,"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":1143,"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/pages\/18\/revisions\/1143"}],"wp:attachment":[{"href":"https:\/\/kfac.fr\/ko\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}